{"id":4680,"date":"2024-04-09T10:19:34","date_gmt":"2024-04-09T08:19:34","guid":{"rendered":"https:\/\/www.msd.ch\/de\/?page_id=4680"},"modified":"2024-04-09T10:19:35","modified_gmt":"2024-04-09T08:19:35","slug":"terms-of-use","status":"publish","type":"page","link":"https:\/\/www.msd.ch\/de\/terms-of-use\/","title":{"rendered":"Nutzungsbedingungen"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Nutzungsbedingungen<\/h2>\n\n\n\n<p>MSD Merck Sharp &amp; Dohme AG (MSD) ist eine Schweizer Tochtergesellschaft von Merck &amp; Co., Inc., Rahway, NJ, USA. MSD, Merck &amp; Co., Inc., Rahway, NJ, USA und die weiteren mit ihr verbundenen Gesellschaften sind ein weltweit operierender Pharmakonzern. <\/p>\n\n\n\n<p>MSD stellt Informationen auf ihrer Website msd.ch allgemeinzug\u00e4nglich zur Verf\u00fcgung. \u00dcberdies stellt MSD gewisse Informationen nach einer pers\u00f6nlichen Registrierung elektronisch in einem eNewsletter zur Verf\u00fcgung. Die vorliegenden Nutzungsbedingungen gelten f\u00fcr unsere Website msd.ch und den eNewsletter (\u00abdie Online-Dienste\u00bb). Einzelne speziell bezeichnete Regelungen dieser Nutzungsbedingungen beziehen sich nur auf den eNewsletter.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Akzeptieren dieser Nutzungsbedingungen<\/h3>\n\n\n\n<p>Mit der Benutzung unserer Online-Dienste akzeptieren Sie diese Nutzungsbedingungen gem\u00e4ss den nachstehenden Bestimmungen, insbesondere dass Sie daran gebunden sind und sich daran halten. Falls Sie damit nicht einverstanden sind, bitten wir Sie, unsere Online-Dienste nicht zu benutzen und die darin enthaltenen Informationen nicht zu beachten. MSD beh\u00e4lt sich das Recht vor, diese Nutzungsbedingungen von Zeit zu Zeit zu \u00e4ndern. MSD wird diese \u00c4nderungen sowie das Datum ihres Inkrafttretens jeweils auf der Website bei den aktuellen Nutzungsbedingungen bekannt geben. Die aktuelle anwendbare Version dieser Nutzungsbedingungen k\u00f6nnen Sie sich jederzeit \u00fcber einen Link am Ende jeder Seite innerhalb dieser Website bzw. im eNewsletter ansehen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Geltungsbereich<\/h3>\n\n\n\n<p>Diese Nutzungsbedingungen sind auf die Online-Dienste von MSD anwendbar. Merck &amp; Co., Inc., Rahway, NJ, USA und die weiteren mit Merck &amp; Co., Inc., Rahway, NJ, USA und MSD verbundenen Gesellschaften betreiben eigene Websites und bieten eigene Dienstleistungen an, f\u00fcr die jeweils so, wie es dort angegeben ist, ihre eigenen Bedingungen gelten. In Bezug auf den Datenschutz, einschliesslich allenfalls erforderlicher Registrierungen Ihrerseits, sind zudem spezielle Bestimmungen (<a href=\"https:\/\/www.msdprivacy.com\/sw\/de\/index.html\">Datenschutz<\/a>) anwendbar.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Medizinische Informationen \/ gesundheitliche Probleme<\/h3>\n\n\n\n<p>Obwohl die Online-Dienste von MSD m\u00f6glicherweise allgemeine Informationen \u00fcber Gesundheitsprobleme und deren Behandlung beinhalten, sollten Sie baldm\u00f6glichst Ihren Arzt oder Ihre Gesundheitsf\u00fcrsorgeeinrichtung aufsuchen, falls Sie gesundheitliche Probleme haben. MSD bietet keine speziell auf die einzelne Person bezogenen medizinischen Diagnosen oder patientenspezifische Ratschl\u00e4ge zur Behandlung an. Nur Ihr Arzt oder eine andere Fachperson kann eine Diagnose stellen und die f\u00fcr Sie pers\u00f6nlich bestm\u00f6gliche Behandlung festlegen. Die auf dieser Website ver\u00f6ffentlichten Informationen werden ausschliesslich zu Informationszwecken zur Verf\u00fcgung gestellt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Beschreibung der Dienstleistungen<\/h3>\n\n\n\n<p>Die Online-Dienste von MSD enthalten Informationen \u00fcber MSD und ihre verschiedenen Produkte. Gewisse Online-Dienste richten sich an ein spezifisches Publikum, einschliesslich Arbeitnehmer, Kunden und Aktion\u00e4re, an Personen, die im Gesundheitsbereich t\u00e4tig sind oder an die Allgemeinheit. F\u00fchlen Sie sich frei, unsere Website Ihren W\u00fcnschen entsprechend durchzubl\u00e4ttern. Ihr Zugriff auf die in unseren Online-Diensten enthaltenen Informationen sowie deren Nutzung unterliegen diesen Nutzungsbedingungen sowie allen anwendbaren Gesetzen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Korrektheit Ihrer eigenen Eingaben<\/h3>\n\n\n\n<p>Als Benutzer unserer Online-Dienste haften Sie f\u00fcr die Korrektheit der Informationen, die Sie MSD \u00fcbermitteln, so zum Beispiel f\u00fcr die Angabe Ihres Berufes. Sollten Sie auf Informationen von MSD antworten, beispielsweise ein Feedback abgeben oder Daten wie zum Beispiel Fragen, Kommentare, Anregungen oder \u00c4hnliches \u00fcbermitteln, werden solche Informationen als nicht vertraulich erachtet. MSD hat bez\u00fcglich solcher Informationen keinerlei Pflichten und ist frei, diese Informationen unbeschr\u00e4nkt zu vervielf\u00e4ltigen und zu benutzen sowie diese im Rahmen der Datenschutz-Regelungen Dritten bekannt zu geben und zu verteilen. MSD steht es frei, jegliche Ideen, Konzepte, jegliches Know-how oder jegliche Techniken, die in solchen Informationen enthalten sind, zu beliebigen Zwecken zu verwenden, insbesondere zur Entwicklung, Herstellung und zum Vertrieb von Produkten.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">eNewsletter<\/h3>\n\n\n\n<p>Die Nutzung des eNewsletters setzt eine Registrierung voraus. Registrieren k\u00f6nnen sich nur medizinische Fachpersonen mit einer Berufsaus\u00fcbungsbewilligung in der Schweiz. Mit der Anmeldung f\u00fcr den eNewsletter best\u00e4tigt der Nutzer, eine in der Schweiz niedergelassene medizinische Fachperson zu sein. MSD kann die Angaben in geeigneter Weise \u00fcberpr\u00fcfen und ist frei, eine Registrierung ohne Angabe von Gr\u00fcnden zu verweigern.<\/p>\n\n\n\n<p>Der eNewsletter von MSD enth\u00e4lt Informationen aus spezifischen Fachgebieten und sonstige aktuelle Informationen aus dem Gesundheitsbereich, wie beispielsweise neueste Forschungsergebnisse und Fortbildungsm\u00f6glichkeiten. Der eNewsletter enth\u00e4lt auch Informationen \u00fcber MSD und ihre verschiedenen Produkte. Die Informationen sind f\u00fcr den Adressaten pers\u00f6nlich bestimmt.<\/p>\n\n\n\n<p>MSD schickt dem Adressaten den eNewsletter jeweils per E-Mail zu. Ein Anspruch des Nutzers auf diesen Service besteht nicht. MSD beh\u00e4lt sich vor, den Versand des eNewsletters jederzeit ohne Vorank\u00fcndigung auszusetzen oder einzustellen. Der Nutzer seinerseits kann jederzeit das Abonnement des eNewsletters k\u00fcndigen, insbesondere durch Abmelden unter dem Men\u00fcpunkt \u00abeNewsletter abbestellen\u00bb.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Links zu anderen Websites<\/h3>\n\n\n\n<p>Auf Websites und im eNewsletter von MSD sind Links zu anderen Websites enthalten, von denen einige MSD und andere nicht MSD oder mit ihr verbundenen Gesellschaften geh\u00f6ren. MSD \u00fcbernimmt keine Haftung f\u00fcr den Inhalt der nicht MSD geh\u00f6renden Websites, auf die wir verweisen. Die Online-Dienste von MSD enthalten keine Inhalte von Websites von Drittparteien; es ist jedoch m\u00f6glich, dass von Online-Diensten von MSD auf andere Websites von mit MSD verbundenen Gesellschaften verwiesen wird, welche Inhalte Dritter enthalten. Solche Websites unterliegen ihren eigenen Nutzungsbedingungen, die auf den jeweiligen Websites aufgef\u00fchrt und abgerufen werden k\u00f6nnen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Immaterialg\u00fcter- und andere Rechte<\/h3>\n\n\n\n<p>MSD ist Eigent\u00fcmerin und Anbieterin der Online-Dienste. S\u00e4mtliche in unseren Online-Diensten verwendeten Marken, Namen, Titel, Logos, Bilder, Designs, Texte und andere Materialien geh\u00f6ren MSD oder einer Gesellschaft des Konzerns Merck &amp; Co., Inc., Rahway, NJ, USA oder einem Vertragspartner derselben. Durch das Aufrufen, Herunterladen, Empfangen oder Kopieren von Informationen aus unseren Online-Diensten werden keinerlei Rechte (Nutzungs-, Lizenz- oder Immaterialg\u00fcterrechte) erworben oder \u00fcbertragen. Das (vollst\u00e4ndige oder teilweise) Reproduzieren, \u00dcbermitteln (elektronisch oder mit anderen Mitteln), Modifizieren, Verkn\u00fcpfen oder Benutzen unserer Online-Dienste und der darin enthaltenen Informationen f\u00fcr \u00f6ffentliche oder kommerzielle Zwecke ist ohne vorherige schriftliche Zustimmung von MSD untersagt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Gew\u00e4hrleistungsausschluss<\/h3>\n\n\n\n<p>MSD hat die angemessenen Massnahmen getroffen, um die Verl\u00e4sslichkeit der mit ihren Online-Diensten verbreiteten Informationen sicherzustellen. Jedoch akzeptieren Sie mit der Benutzung unserer Online-Dienste die darin angebotenen Informationen, so wie sie ver\u00f6ffentlicht werden. MSD gibt f\u00fcr die Genauigkeit, den Inhalt, die Vollst\u00e4ndigkeit, die Verl\u00e4sslichkeit, die Praktikabilit\u00e4t oder Gesetzm\u00e4ssigkeit der in ihren Online-Diensten enthaltenen Informationen weder ausdr\u00fccklich noch stillschweigend eine Garantie oder Zusicherung ab; derselbe Ausschluss jeder Gew\u00e4hrleistung von MSD gilt f\u00fcr die Marktg\u00e4ngigkeit, die Geeignetheit zu einem bestimmten Zweck und f\u00fcr die Nichtverletzung von Eigentumsrechten. Irrt\u00fcmlich falsche Angaben, Druckfehler und technische Ungenauigkeiten k\u00f6nnen nicht ausgeschlossen werden. MSD \u00fcbernimmt auch keine Verantwortung und Haftung f\u00fcr Sch\u00e4den an Ihrem Computer oder Ihrer Ausr\u00fcstung (z.B. durch Viren), die infolge Ihres Zugriffs oder der Benutzung unserer Online-Dienste entstehen. MSD beh\u00e4lt sich vor, den Inhalt ihrer Website jederzeit ohne Vorank\u00fcndigung zu \u00e4ndern.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Verletzung dieser Nutzungsbedingungen<\/h3>\n\n\n\n<p>MSD ist berechtigt, gegen Verletzungen dieser Nutzungsbestimmungen durch Sie rechtlich vorzugehen. Insbesondere beh\u00e4lt sich MSD diesfalls vor, Ihr Konto bei MSD zu sperren oder aufzul\u00f6sen. MSD beh\u00e4lt sich \u00fcberdies vor, Ihr Konto zu l\u00f6schen, sofern dessen Nutzung gegen geltendes Recht verst\u00f6sst. Falls Ihr Verstoss oder Aktivit\u00e4ten, die unter Verwendung Ihres Kontos vorgenommen werden, Dritten einen Schaden zuf\u00fcgen, sind Sie verpflichtet, MSD schadlos zu halten, insbesondere von jeglichen Verm\u00f6genssch\u00e4den, Sachsch\u00e4den und Kosten sowie von jeglichen Rechtsanspr\u00fcchen und Klagen. Sie sind daher verpflichtet, ein allf\u00e4lliges Passwort geheim zu halten und den Zugang zu ihrem Konto sorgf\u00e4ltig zu sichern. MSD verschl\u00fcsselt das Passwort von Benutzern, gibt es nicht an Dritte weiter und fragt nie per E-Mail oder Telefon einen Benutzer nach seinem Passwort. MSD selbst kennt das Passwort nicht und hat keinen Zugriff darauf. Ihr Konto ist nicht \u00fcbertragbar. MSD unterst\u00fctzt die Vollstreckungsbeh\u00f6rden und vollzieht Gerichtsbeschl\u00fcsse, welche MSD auffordern, die Identit\u00e4t einer Person mitzuteilen, welche im Zusammenhang mit Online-Diensten von MSD m\u00f6glicherweise strafbare Handlungen durchf\u00fchrte. Sie sind verpflichtet, MSD umgehend zu informieren, wenn es Anhaltspunkte daf\u00fcr gibt, dass ein Konto von Dritten missbraucht wird.<\/p>\n\n\n\n<p>Diese Nutzungsbedingungen und Ihre Nutzung unserer Online-Dienste unterliegen Schweizer Recht, unter Ausschluss des Kollisionsrechts.<\/p>\n\n\n\n<p>Stand: April 2024<\/p>\n\n\n\n<p><sup>CH-NON-00909, 04\/2024<\/sup><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nutzungsbedingungen MSD Merck Sharp &amp; Dohme AG (MSD) ist eine Schweizer Tochtergesellschaft von Merck &amp; Co., Inc., Rahway, NJ, USA. MSD, Merck &amp; Co., Inc., Rahway, NJ, USA und die weiteren mit ihr verbundenen Gesellschaften sind ein weltweit operierender Pharmakonzern. MSD stellt Informationen auf ihrer Website msd.ch allgemeinzug\u00e4nglich zur Verf\u00fcgung. \u00dcberdies stellt MSD gewisse Informationen [&hellip;]<\/p>\n","protected":false},"author":283,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"bdl_company_name":[],"bdl_item_external_link":[],"editor_notices":[],"footnotes":""},"class_list":["post-4680","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.9.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nutzungsbedingungen - msd.ch<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.msd.ch\/de\/terms-of-use\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nutzungsbedingungen - msd.ch\" \/>\n<meta property=\"og:description\" content=\"Nutzungsbedingungen MSD Merck Sharp &amp; Dohme AG (MSD) ist eine Schweizer Tochtergesellschaft von Merck &amp; Co., Inc., Rahway, NJ, USA. MSD, Merck &amp; Co., Inc., Rahway, NJ, USA und die weiteren mit ihr verbundenen Gesellschaften sind ein weltweit operierender Pharmakonzern. MSD stellt Informationen auf ihrer Website msd.ch allgemeinzug\u00e4nglich zur Verf\u00fcgung. \u00dcberdies stellt MSD gewisse Informationen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.msd.ch\/de\/terms-of-use\/\" \/>\n<meta property=\"og:site_name\" content=\"msd.ch\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-09T08:19:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.msd.ch\/de\/terms-of-use\/\",\"url\":\"https:\/\/www.msd.ch\/de\/terms-of-use\/\",\"name\":\"Nutzungsbedingungen - msd.ch\",\"isPartOf\":{\"@id\":\"https:\/\/www.msd.ch\/de\/#website\"},\"datePublished\":\"2024-04-09T08:19:34+00:00\",\"dateModified\":\"2024-04-09T08:19:35+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.msd.ch\/de\/terms-of-use\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.msd.ch\/de\/#website\",\"url\":\"https:\/\/www.msd.ch\/de\/\",\"name\":\"msd.ch\",\"description\":\"MSD erforscht und entwickelt Medikamente und Impfstoffe, die Leben retten und die Gesundheit von Patienten verbessern sollen. In der Schweiz setzen sich 1000 Mitarbeitende in Luzern und Z\u00fcrich daf\u00fcr ein.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.msd.ch\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nutzungsbedingungen - msd.ch","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.msd.ch\/de\/terms-of-use\/","og_locale":"en_US","og_type":"article","og_title":"Nutzungsbedingungen - msd.ch","og_description":"Nutzungsbedingungen MSD Merck Sharp &amp; Dohme AG (MSD) ist eine Schweizer Tochtergesellschaft von Merck &amp; Co., Inc., Rahway, NJ, USA. MSD, Merck &amp; Co., Inc., Rahway, NJ, USA und die weiteren mit ihr verbundenen Gesellschaften sind ein weltweit operierender Pharmakonzern. MSD stellt Informationen auf ihrer Website msd.ch allgemeinzug\u00e4nglich zur Verf\u00fcgung. \u00dcberdies stellt MSD gewisse Informationen [&hellip;]","og_url":"https:\/\/www.msd.ch\/de\/terms-of-use\/","og_site_name":"msd.ch","article_modified_time":"2024-04-09T08:19:35+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.msd.ch\/de\/terms-of-use\/","url":"https:\/\/www.msd.ch\/de\/terms-of-use\/","name":"Nutzungsbedingungen - msd.ch","isPartOf":{"@id":"https:\/\/www.msd.ch\/de\/#website"},"datePublished":"2024-04-09T08:19:34+00:00","dateModified":"2024-04-09T08:19:35+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.msd.ch\/de\/terms-of-use\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.msd.ch\/de\/#website","url":"https:\/\/www.msd.ch\/de\/","name":"msd.ch","description":"MSD erforscht und entwickelt Medikamente und Impfstoffe, die Leben retten und die Gesundheit von Patienten verbessern sollen. In der Schweiz setzen sich 1000 Mitarbeitende in Luzern und Z\u00fcrich daf\u00fcr ein.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.msd.ch\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.msd.ch\/de\/wp-json\/wp\/v2\/pages\/4680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.msd.ch\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.msd.ch\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.msd.ch\/de\/wp-json\/wp\/v2\/users\/283"}],"replies":[{"embeddable":true,"href":"https:\/\/www.msd.ch\/de\/wp-json\/wp\/v2\/comments?post=4680"}],"version-history":[{"count":4,"href":"https:\/\/www.msd.ch\/de\/wp-json\/wp\/v2\/pages\/4680\/revisions"}],"predecessor-version":[{"id":11339,"href":"https:\/\/www.msd.ch\/de\/wp-json\/wp\/v2\/pages\/4680\/revisions\/11339"}],"wp:attachment":[{"href":"https:\/\/www.msd.ch\/de\/wp-json\/wp\/v2\/media?parent=4680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}